{"id":51,"count":6,"description":"","link":"https:\/\/www.hirsiset.com\/en\/project-category\/unique-homes-en\/","name":"Unique Homes","slug":"unique-homes-en","taxonomy":"dt_portfolio_category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hirsiset - Unique Homes collection log houses log villas log homes log apartment<\/title>\n<meta name=\"description\" content=\"Hirsiset Unique Homes collection log houses log villas log homes log apartment. Unique and original Log buildings that stand the test of time.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hirsiset.com\/en\/project-category\/unique-homes-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hirsiset - Unique Homes collection log houses log villas log homes log apartment\" \/>\n<meta property=\"og:description\" content=\"Hirsiset Unique Homes collection log houses log villas log homes log apartment. Unique and original Log buildings that stand the test of time.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hirsiset.com\/en\/project-category\/unique-homes-en\/\" \/>\n<meta property=\"og:site_name\" content=\"Hirsiset\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@hirsiset\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.hirsiset.com\\\/en\\\/project-category\\\/unique-homes-en\\\/\",\"url\":\"https:\\\/\\\/www.hirsiset.com\\\/en\\\/project-category\\\/unique-homes-en\\\/\",\"name\":\"Hirsiset - Unique Homes collection log houses log villas log homes log apartment\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hirsiset.com\\\/en\\\/#website\"},\"description\":\"Hirsiset Unique Homes collection log houses log villas log homes log apartment. Unique and original Log buildings that stand the test of time.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hirsiset.com\\\/en\\\/project-category\\\/unique-homes-en\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hirsiset.com\\\/en\\\/project-category\\\/unique-homes-en\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.hirsiset.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Unique Homes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hirsiset.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.hirsiset.com\\\/en\\\/\",\"name\":\"Hirsiset\",\"description\":\"Log houses with over 30 years of experience\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.hirsiset.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hirsiset.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.hirsiset.com\\\/en\\\/#organization\",\"name\":\"Oulun Hirsiset Oy\",\"url\":\"https:\\\/\\\/www.hirsiset.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.hirsiset.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.hirsiset.com\\\/wp-content\\\/uploads\\\/Hirsiset_logo65px.png\",\"contentUrl\":\"https:\\\/\\\/www.hirsiset.com\\\/wp-content\\\/uploads\\\/Hirsiset_logo65px.png\",\"width\":299,\"height\":65,\"caption\":\"Oulun Hirsiset Oy\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hirsiset.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Hirsiset\\\/\",\"https:\\\/\\\/x.com\\\/hirsiset\",\"https:\\\/\\\/www.instagram.com\\\/hirsiset_oy\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hirsiset - Unique Homes collection log houses log villas log homes log apartment","description":"Hirsiset Unique Homes collection log houses log villas log homes log apartment. Unique and original Log buildings that stand the test of time.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hirsiset.com\/en\/project-category\/unique-homes-en\/","og_locale":"en_US","og_type":"article","og_title":"Hirsiset - Unique Homes collection log houses log villas log homes log apartment","og_description":"Hirsiset Unique Homes collection log houses log villas log homes log apartment. Unique and original Log buildings that stand the test of time.","og_url":"https:\/\/www.hirsiset.com\/en\/project-category\/unique-homes-en\/","og_site_name":"Hirsiset","twitter_card":"summary_large_image","twitter_site":"@hirsiset","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.hirsiset.com\/en\/project-category\/unique-homes-en\/","url":"https:\/\/www.hirsiset.com\/en\/project-category\/unique-homes-en\/","name":"Hirsiset - Unique Homes collection log houses log villas log homes log apartment","isPartOf":{"@id":"https:\/\/www.hirsiset.com\/en\/#website"},"description":"Hirsiset Unique Homes collection log houses log villas log homes log apartment. Unique and original Log buildings that stand the test of time.","breadcrumb":{"@id":"https:\/\/www.hirsiset.com\/en\/project-category\/unique-homes-en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.hirsiset.com\/en\/project-category\/unique-homes-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.hirsiset.com\/en\/"},{"@type":"ListItem","position":2,"name":"Unique Homes"}]},{"@type":"WebSite","@id":"https:\/\/www.hirsiset.com\/en\/#website","url":"https:\/\/www.hirsiset.com\/en\/","name":"Hirsiset","description":"Log houses with over 30 years of experience","publisher":{"@id":"https:\/\/www.hirsiset.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hirsiset.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.hirsiset.com\/en\/#organization","name":"Oulun Hirsiset Oy","url":"https:\/\/www.hirsiset.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.hirsiset.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.hirsiset.com\/wp-content\/uploads\/Hirsiset_logo65px.png","contentUrl":"https:\/\/www.hirsiset.com\/wp-content\/uploads\/Hirsiset_logo65px.png","width":299,"height":65,"caption":"Oulun Hirsiset Oy"},"image":{"@id":"https:\/\/www.hirsiset.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Hirsiset\/","https:\/\/x.com\/hirsiset","https:\/\/www.instagram.com\/hirsiset_oy\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.hirsiset.com\/en\/wp-json\/wp\/v2\/dt_portfolio_category\/51","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hirsiset.com\/en\/wp-json\/wp\/v2\/dt_portfolio_category"}],"about":[{"href":"https:\/\/www.hirsiset.com\/en\/wp-json\/wp\/v2\/taxonomies\/dt_portfolio_category"}],"wp:post_type":[{"href":"https:\/\/www.hirsiset.com\/en\/wp-json\/wp\/v2\/dt_portfolio?dt_portfolio_category=51"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}