{"id":36588,"date":"2019-04-03T13:37:27","date_gmt":"2019-04-03T10:37:27","guid":{"rendered":"https:\/\/www.hirsiset.com\/gallery\/villa-valtanen\/"},"modified":"2019-04-03T13:37:27","modified_gmt":"2019-04-03T10:37:27","slug":"villa-valtanen","status":"publish","type":"dt_gallery","link":"https:\/\/www.hirsiset.com\/cs\/gallery\/villa-valtanen\/","title":{"rendered":"Log Cottage Villa Valtanen"},"content":{"rendered":"<p>Hirsiset Log Cottage Villa Valtanen. Check out our log house log cabin or log cottage collections and choose yours.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hirsiset Log Cottage Villa Valtanen. Check out our log house log cabin or log cottage collections and choose yours.<\/p>\n","protected":false},"author":2,"featured_media":6526,"comment_status":"closed","ping_status":"closed","template":"","dt_gallery_category":[269],"class_list":["post-36588","dt_gallery","type-dt_gallery","status-publish","has-post-thumbnail","hentry","dt_gallery_category-photogallery-cs","dt_gallery_category-269","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Log Cottage Villa Valtanen - Hirsiset<\/title>\n<meta name=\"description\" content=\"Tutustu Hirsiset hirsitalo, hirsikoti tai hirsihuvila -mallistoihimme ja valitse omasi laadukaista taidonn\u00e4ytteist\u00e4mme. Astu peremm\u00e4lle ja katso milt\u00e4 hirsitalo sis\u00e4puolelta n\u00e4ytt\u00e4\u00e4\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hirsiset.com\/cs\/gallery\/villa-valtanen\/\" \/>\n<meta property=\"og:locale\" content=\"cs_CZ\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Log Cottage Villa Valtanen - Hirsiset\" \/>\n<meta property=\"og:description\" content=\"Tutustu Hirsiset hirsitalo, hirsikoti tai hirsihuvila -mallistoihimme ja valitse omasi laadukaista taidonn\u00e4ytteist\u00e4mme. Astu peremm\u00e4lle ja katso milt\u00e4 hirsitalo sis\u00e4puolelta n\u00e4ytt\u00e4\u00e4\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hirsiset.com\/cs\/gallery\/villa-valtanen\/\" \/>\n<meta property=\"og:site_name\" content=\"Hirsiset\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Hirsiset\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@hirsiset\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hirsiset.com\\\/cs\\\/gallery\\\/villa-valtanen\\\/\",\"url\":\"https:\\\/\\\/www.hirsiset.com\\\/cs\\\/gallery\\\/villa-valtanen\\\/\",\"name\":\"Log Cottage Villa Valtanen - Hirsiset\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hirsiset.com\\\/cs\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.hirsiset.com\\\/cs\\\/gallery\\\/villa-valtanen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hirsiset.com\\\/cs\\\/gallery\\\/villa-valtanen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hirsiset.com\\\/wp-content\\\/uploads\\\/VillaValtanen_outside.jpg\",\"datePublished\":\"2019-04-03T10:37:27+00:00\",\"description\":\"Tutustu Hirsiset hirsitalo, hirsikoti tai hirsihuvila -mallistoihimme ja valitse omasi laadukaista taidonn\u00e4ytteist\u00e4mme. Astu peremm\u00e4lle ja katso milt\u00e4 hirsitalo sis\u00e4puolelta n\u00e4ytt\u00e4\u00e4\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hirsiset.com\\\/cs\\\/gallery\\\/villa-valtanen\\\/#breadcrumb\"},\"inLanguage\":\"cs\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hirsiset.com\\\/cs\\\/gallery\\\/villa-valtanen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"cs\",\"@id\":\"https:\\\/\\\/www.hirsiset.com\\\/cs\\\/gallery\\\/villa-valtanen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.hirsiset.com\\\/wp-content\\\/uploads\\\/VillaValtanen_outside.jpg\",\"contentUrl\":\"https:\\\/\\\/www.hirsiset.com\\\/wp-content\\\/uploads\\\/VillaValtanen_outside.jpg\",\"width\":1400,\"height\":933,\"caption\":\"Villa Valtanen outside\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hirsiset.com\\\/cs\\\/gallery\\\/villa-valtanen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.hirsiset.com\\\/cs\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Photo Albums\",\"item\":\"https:\\\/\\\/www.hirsiset.com\\\/cs\\\/gallery\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Log Cottage Villa Valtanen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hirsiset.com\\\/cs\\\/#website\",\"url\":\"https:\\\/\\\/www.hirsiset.com\\\/cs\\\/\",\"name\":\"Hirsiset\",\"description\":\"Srubov\u00e9 domy s v\u00edce ne\u017e 30 lety zku\u0161enost\u00ed\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.hirsiset.com\\\/cs\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hirsiset.com\\\/cs\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"cs\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.hirsiset.com\\\/cs\\\/#organization\",\"name\":\"Oulun Hirsiset Oy\",\"url\":\"https:\\\/\\\/www.hirsiset.com\\\/cs\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"cs\",\"@id\":\"https:\\\/\\\/www.hirsiset.com\\\/cs\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.hirsiset.com\\\/wp-content\\\/uploads\\\/Hirsiset_logo65px.png\",\"contentUrl\":\"https:\\\/\\\/www.hirsiset.com\\\/wp-content\\\/uploads\\\/Hirsiset_logo65px.png\",\"width\":299,\"height\":65,\"caption\":\"Oulun Hirsiset Oy\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hirsiset.com\\\/cs\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Hirsiset\\\/\",\"https:\\\/\\\/x.com\\\/hirsiset\",\"https:\\\/\\\/www.instagram.com\\\/hirsiset_oy\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Log Cottage Villa Valtanen - Hirsiset","description":"Tutustu Hirsiset hirsitalo, hirsikoti tai hirsihuvila -mallistoihimme ja valitse omasi laadukaista taidonn\u00e4ytteist\u00e4mme. Astu peremm\u00e4lle ja katso milt\u00e4 hirsitalo sis\u00e4puolelta n\u00e4ytt\u00e4\u00e4","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hirsiset.com\/cs\/gallery\/villa-valtanen\/","og_locale":"cs_CZ","og_type":"article","og_title":"Log Cottage Villa Valtanen - Hirsiset","og_description":"Tutustu Hirsiset hirsitalo, hirsikoti tai hirsihuvila -mallistoihimme ja valitse omasi laadukaista taidonn\u00e4ytteist\u00e4mme. Astu peremm\u00e4lle ja katso milt\u00e4 hirsitalo sis\u00e4puolelta n\u00e4ytt\u00e4\u00e4","og_url":"https:\/\/www.hirsiset.com\/cs\/gallery\/villa-valtanen\/","og_site_name":"Hirsiset","article_publisher":"https:\/\/www.facebook.com\/Hirsiset\/","twitter_card":"summary_large_image","twitter_site":"@hirsiset","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.hirsiset.com\/cs\/gallery\/villa-valtanen\/","url":"https:\/\/www.hirsiset.com\/cs\/gallery\/villa-valtanen\/","name":"Log Cottage Villa Valtanen - Hirsiset","isPartOf":{"@id":"https:\/\/www.hirsiset.com\/cs\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.hirsiset.com\/cs\/gallery\/villa-valtanen\/#primaryimage"},"image":{"@id":"https:\/\/www.hirsiset.com\/cs\/gallery\/villa-valtanen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hirsiset.com\/wp-content\/uploads\/VillaValtanen_outside.jpg","datePublished":"2019-04-03T10:37:27+00:00","description":"Tutustu Hirsiset hirsitalo, hirsikoti tai hirsihuvila -mallistoihimme ja valitse omasi laadukaista taidonn\u00e4ytteist\u00e4mme. Astu peremm\u00e4lle ja katso milt\u00e4 hirsitalo sis\u00e4puolelta n\u00e4ytt\u00e4\u00e4","breadcrumb":{"@id":"https:\/\/www.hirsiset.com\/cs\/gallery\/villa-valtanen\/#breadcrumb"},"inLanguage":"cs","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hirsiset.com\/cs\/gallery\/villa-valtanen\/"]}]},{"@type":"ImageObject","inLanguage":"cs","@id":"https:\/\/www.hirsiset.com\/cs\/gallery\/villa-valtanen\/#primaryimage","url":"https:\/\/www.hirsiset.com\/wp-content\/uploads\/VillaValtanen_outside.jpg","contentUrl":"https:\/\/www.hirsiset.com\/wp-content\/uploads\/VillaValtanen_outside.jpg","width":1400,"height":933,"caption":"Villa Valtanen outside"},{"@type":"BreadcrumbList","@id":"https:\/\/www.hirsiset.com\/cs\/gallery\/villa-valtanen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.hirsiset.com\/cs\/"},{"@type":"ListItem","position":2,"name":"Photo Albums","item":"https:\/\/www.hirsiset.com\/cs\/gallery\/"},{"@type":"ListItem","position":3,"name":"Log Cottage Villa Valtanen"}]},{"@type":"WebSite","@id":"https:\/\/www.hirsiset.com\/cs\/#website","url":"https:\/\/www.hirsiset.com\/cs\/","name":"Hirsiset","description":"Srubov\u00e9 domy s v\u00edce ne\u017e 30 lety zku\u0161enost\u00ed","publisher":{"@id":"https:\/\/www.hirsiset.com\/cs\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hirsiset.com\/cs\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"cs"},{"@type":"Organization","@id":"https:\/\/www.hirsiset.com\/cs\/#organization","name":"Oulun Hirsiset Oy","url":"https:\/\/www.hirsiset.com\/cs\/","logo":{"@type":"ImageObject","inLanguage":"cs","@id":"https:\/\/www.hirsiset.com\/cs\/#\/schema\/logo\/image\/","url":"https:\/\/www.hirsiset.com\/wp-content\/uploads\/Hirsiset_logo65px.png","contentUrl":"https:\/\/www.hirsiset.com\/wp-content\/uploads\/Hirsiset_logo65px.png","width":299,"height":65,"caption":"Oulun Hirsiset Oy"},"image":{"@id":"https:\/\/www.hirsiset.com\/cs\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Hirsiset\/","https:\/\/x.com\/hirsiset","https:\/\/www.instagram.com\/hirsiset_oy\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.hirsiset.com\/cs\/wp-json\/wp\/v2\/dt_gallery\/36588","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hirsiset.com\/cs\/wp-json\/wp\/v2\/dt_gallery"}],"about":[{"href":"https:\/\/www.hirsiset.com\/cs\/wp-json\/wp\/v2\/types\/dt_gallery"}],"author":[{"embeddable":true,"href":"https:\/\/www.hirsiset.com\/cs\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hirsiset.com\/cs\/wp-json\/wp\/v2\/comments?post=36588"}],"version-history":[{"count":0,"href":"https:\/\/www.hirsiset.com\/cs\/wp-json\/wp\/v2\/dt_gallery\/36588\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hirsiset.com\/cs\/wp-json\/wp\/v2\/media\/6526"}],"wp:attachment":[{"href":"https:\/\/www.hirsiset.com\/cs\/wp-json\/wp\/v2\/media?parent=36588"}],"wp:term":[{"taxonomy":"dt_gallery_category","embeddable":true,"href":"https:\/\/www.hirsiset.com\/cs\/wp-json\/wp\/v2\/dt_gallery_category?post=36588"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}